{"id":462,"count":3,"description":"","link":"https:\/\/cri-one.com\/blog\/category\/patent-process\/","name":"Patent Process","slug":"patent-process","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/cri-one.com\/blog\/wp-json\/wp\/v2\/categories\/462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cri-one.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/cri-one.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/cri-one.com\/blog\/wp-json\/wp\/v2\/posts?categories=462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}